{"id":2489,"date":"2024-10-12T14:05:37","date_gmt":"2024-10-12T12:05:37","guid":{"rendered":"https:\/\/www.cardenaldonmarcelo.es\/?p=2489"},"modified":"2024-10-12T17:26:51","modified_gmt":"2024-10-12T15:26:51","slug":"sacerdote-y-liturgo","status":"publish","type":"post","link":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/2024\/10\/12\/sacerdote-y-liturgo\/","title":{"rendered":"Sacerdote y liturgo"},"content":{"rendered":"\n<p class=\"has-text-align-center has-small-font-size\">Por d. Juan Miguel Ferrer Grenesche, Vicario General de la Archidi\u00f3cesis de Toledo, Publicado en el<em>Padrenuestro<\/em> 29 de junio de 1991<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Resulta para m\u00ed un reto y un riesgo el presentar en unas pocas l\u00edneas la imagen de don Marcelo Gonz\u00e1lez Mart\u00edn. Ahora bien, cualquier semblanza sobre sus cincuenta a\u00f1os de sacerdocio que olvidase esta dimensi\u00f3n ser\u00eda incompleta. Por eso, lleno de cordial agradecimiento hacia su persona y su sacerdocio, intentar\u00e9 cumplir este cometido. No pretendo reflejar aqu\u00ed su magisterio abundante sobre la Liturgia. Tampoco sus muchas iniciativas pastorales, antes o despu\u00e9s, siendo <strong>Presidente de la Comisi\u00f3n Episcopal de Liturgia<\/strong>. Tan solo quiero destacar algunos rasgos que a m\u00ed me han impresionado, de su figura de liturgo.<\/p>\n\n\n\n<p>Al decir esto apunto al n\u00facleo de su sacerdocio.<\/p>\n\n\n\n<p>Ser liturgo no es para el sacerdote simplemente una dimensi\u00f3n de su tarea externa, porque el sacerdocio cristiano no es un a\u00f1adido a la personalidad del sacerdote.<\/p>\n\n\n\n<p>Ser liturgo va m\u00e1s all\u00e1 de ser celebrante o presidente de una asamblea lit\u00fargica. Ser liturgo es un modo de concebir la propia existencia sacerdotalmente.<\/p>\n\n\n\n<p>Ser liturgo es el modo cristiano de unificar y jerarquizar la vida y el ministerio sacerdotal, centrado en Dios y vivido eclesialmente, desde una experiencia de docilidad y comuni\u00f3n.<\/p>\n\n\n\n<p><strong>Liturgo evangelizador<\/strong><\/p>\n\n\n\n<p>Siempre me ha impresionado la capacidad emprendedora e imaginativa de don Marcelo. Una sed, un celo por hacer llevar la buena nueva a todos los hombres, de toda condici\u00f3n, de todo pa\u00eds. La Liturgia vivida como fuente crea corazones evangelizadores y misioneros, despierta inquietudes, abre horizontes. Como cima, hace que todos esos proyectos, afanes e inquietudes tengan un norte claro y preciso, lleguen a Dios. Para m\u00ed este es uno de los rasgos m\u00e1s destacados de la estampa sacerdotal del Cardenal Gonz\u00e1lez Mart\u00edn.<\/p>\n\n\n\n<p><strong>Liturgo di\u00e1cono<\/strong><\/p>\n\n\n\n<p>Entre las muchas inquietudes apost\u00f3licas de don Marcelo destaca su constante preocupaci\u00f3n por la atenci\u00f3n a los necesitados y a los pobres. Esfuerzo que unas veces se ha transformado en el campo de la doctrina social de la Iglesia y otras muchas en muy diversas obras sociales. La diacon\u00eda como rasgo esencial del sacerdocio cristiano, no abandona nunca al presb\u00edtero ni al obispo y se actualiza cotidianamente en la celebraci\u00f3n lit\u00fargica, como exigencia de oblaci\u00f3n personal y como fuente de conversi\u00f3n hacia Dios y hacia los hermanos.<\/p>\n\n\n\n<p><strong>Liturgo santificador<\/strong><\/p>\n\n\n\n<p>La acci\u00f3n santificadora del sacerdote se realiza principalmente mediante la oraci\u00f3n y los sacramentos. Quien conoce a don Marcelo y le ha visto presidir la oraci\u00f3n de la Iglesia o la administraci\u00f3n de alg\u00fan sacramento, percibe inmediatamente la grandeza majestuosa de la acci\u00f3n divina. Uno siente ser testigo y protagonista de algo importante. Las celebraciones lit\u00fargicas merecen respeto porque tocan el misterio de Dios, el misterio de la Iglesia y el misterio del ser humano, todo ello en virtud de la econom\u00eda sacramental. La importancia de vivir unos gestos eficaces, una palabra como creadora, una oraci\u00f3n como comuni\u00f3n es algo que don Marcelo nos recuerda cada vez que nos preside.<\/p>\n\n\n\n<p><strong>Liturgo de comuni\u00f3n<\/strong><\/p>\n\n\n\n<p>La idea de comuni\u00f3n es clave al tratar de la Liturgia que, por su protagonismo divino, nos educa par aun nuevo modo de vivir. Se trata de abandonar toda forma de individualismo para vivir en Dios, en la Iglesia, abierto a los hombres, nuestros hermanos.<\/p>\n\n\n\n<p>Estas disposiciones propias del vivir en comuni\u00f3n aparecen como trazos precisos y fuertes del retrato sacerdotal de don Marcelo. Su perenne afirmaci\u00f3n de la primac\u00eda de Dios en la vida cristiana y en la Teolog\u00eda, predicada oportuna e inoportunamente, su apasionada entrega a la Iglesia, traducida en fidelidad y apertura gozosa a las reformas y cambios propuestos pro su magisterio, su sensibilidad por los temas de la cultura y los rasgos culturales de las diversas regiones donde ha ejercido su ministerio, son manifestaciones externas de este vivir en comuni\u00f3n, rasgo definitorio de la Liturgia cat\u00f3lica. Manifestaci\u00f3n especialmente sensible de esta comuni\u00f3n con los m\u00e1s genuinos rasgos de la cultura de su pueblo ha sido y es su aportaci\u00f3n generosa y fundamental en la recuperaci\u00f3n de la Liturgia Hispano-Moz\u00e1rabe, conservada particularmente en esta sede primada de Toledo; pronto, gracias a don Marcelo, ver\u00e1 la luz su nuevo misal reformado.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por d. Juan Miguel Ferrer Grenesche, Vicario General de la Archidi\u00f3cesis de Toledo, Publicado en elPadrenuestro 29 de junio de 1991 Resulta para m\u00ed un reto y un riesgo el presentar en unas pocas l\u00edneas la imagen de don Marcelo Gonz\u00e1lez Mart\u00edn. Ahora bien, cualquier semblanza sobre sus cincuenta a\u00f1os de sacerdocio que olvidase esta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2498,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"_eb_attr":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[91],"tags":[],"class_list":["post-2489","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-sus-bodas-de-oro"],"jetpack_featured_media_url":"https:\/\/www.cardenaldonmarcelo.es\/wp-content\/uploads\/2024\/10\/ferrer-1.jpg","rttpg_featured_image_url":{"full":["https:\/\/www.cardenaldonmarcelo.es\/wp-content\/uploads\/2024\/10\/ferrer-1.jpg",500,448,false],"landscape":["https:\/\/www.cardenaldonmarcelo.es\/wp-content\/uploads\/2024\/10\/ferrer-1.jpg",500,448,false],"portraits":["https:\/\/www.cardenaldonmarcelo.es\/wp-content\/uploads\/2024\/10\/ferrer-1.jpg",500,448,false],"thumbnail":["https:\/\/www.cardenaldonmarcelo.es\/wp-content\/uploads\/2024\/10\/ferrer-1-150x150.jpg",150,150,true],"medium":["https:\/\/www.cardenaldonmarcelo.es\/wp-content\/uploads\/2024\/10\/ferrer-1-300x269.jpg",300,269,true],"large":["https:\/\/www.cardenaldonmarcelo.es\/wp-content\/uploads\/2024\/10\/ferrer-1.jpg",500,448,false],"1536x1536":["https:\/\/www.cardenaldonmarcelo.es\/wp-content\/uploads\/2024\/10\/ferrer-1.jpg",500,448,false],"2048x2048":["https:\/\/www.cardenaldonmarcelo.es\/wp-content\/uploads\/2024\/10\/ferrer-1.jpg",500,448,false],"kubio-fullhd":["https:\/\/www.cardenaldonmarcelo.es\/wp-content\/uploads\/2024\/10\/ferrer-1.jpg",500,448,false],"jetpack-portfolio-admin-thumb":["https:\/\/www.cardenaldonmarcelo.es\/wp-content\/uploads\/2024\/10\/ferrer-1.jpg",50,45,false]},"rttpg_author":{"display_name":"P. Webmaster","author_link":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/author\/currante\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/www.cardenaldonmarcelo.es\/index.php\/category\/en-sus-bodas-de-oro\/\" rel=\"category tag\">50 aniversario de su sacerdocio<\/a>","rttpg_excerpt":"Por d. Juan Miguel Ferrer Grenesche, Vicario General de la Archidi\u00f3cesis de Toledo, Publicado en elPadrenuestro 29 de junio de 1991 Resulta para m\u00ed un reto y un riesgo el presentar en unas pocas l\u00edneas la imagen de don Marcelo Gonz\u00e1lez Mart\u00edn. Ahora bien, cualquier semblanza sobre sus cincuenta a\u00f1os de sacerdocio que olvidase esta&hellip;","_links":{"self":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/posts\/2489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/comments?post=2489"}],"version-history":[{"count":1,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/posts\/2489\/revisions"}],"predecessor-version":[{"id":2491,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/posts\/2489\/revisions\/2491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/media\/2498"}],"wp:attachment":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/media?parent=2489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/categories?post=2489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/tags?post=2489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}