{"id":720,"date":"2024-09-22T18:53:48","date_gmt":"2024-09-22T16:53:48","guid":{"rendered":"https:\/\/www.cardenaldonmarcelo.es\/?post_type=docs&#038;p=720"},"modified":"2024-09-22T18:53:48","modified_gmt":"2024-09-22T16:53:48","password":"","slug":"actualidad-de-la-vida-contemplativa","status":"publish","type":"docs","link":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/docs\/actualidad-de-la-vida-contemplativa\/","title":{"rendered":"Actualidad de la vida contemplativa"},"content":{"rendered":"\n<p class=\"has-text-align-center has-small-font-size\">Carta pastoral, de mayo de 1977, con motivo del VIII Centenario del Monasterio Cisterciense de San Clemente, de Toledo. Texto publicado en el <em>Bolet\u00edn Oficial del Arzobispado de Toledo,<\/em> mayo 1977.<\/p>\n\n\n\n<p>No hace mucho tiempo, con motivo de la canonizaci\u00f3n de Santa Beatriz de Silva y de la beatificaci\u00f3n de Sor Mar\u00eda de Jes\u00fas, pude referirme, aunque muy brevemente, a algunos valores perennes de la vida contemplativa, siempre nuevos y fecundos en la acci\u00f3n evangelizadora de la Iglesia. Quiero hoy insistir con m\u00e1s detenimiento en el mismo tema, tomando pie de un sencillo acontecimiento que vamos a celebrar en este mismo mes de mayo.<\/p>\n\n\n\n<p>El Monasterio de San Clemente, situado en el coraz\u00f3n mismo de la ciudad de Toledo, cumple ochocientos a\u00f1os de existencia, durante los cuales las religiosas del C\u00edster han dado gloria a Dios y un maravilloso testimonio de perseverancia en el servicio al ideal mon\u00e1stico. Es justo que sus actuales moradoras quieran aprovechar esta circunstancia para agradecer al Se\u00f1or este beneficio insigne, y que nosotros la aprovechemos tambi\u00e9n para ofrecer a nuestros diocesanos la lecci\u00f3n que de este hecho se desprende.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Algunos datos hist\u00f3ricos<\/h2>\n\n\n\n<p>El Monasterio de San Clemente fue fundado a finales del siglo XI o en los comienzos del XII para religiosas benedictinas. Se uni\u00f3 al C\u00edster en 1175. Desde esta fecha han permanecido all\u00ed las religiosas ininterrumpidamente, entregadas a la oraci\u00f3n y al sacrificio por las necesidades del mundo. Ochocientos a\u00f1os de contemplaci\u00f3n y holocausto significan mucho en el seguimiento amoroso de la voluntad de Dios y en el enriquecimiento de la Santa Iglesia.<\/p>\n\n\n\n<p>No es \u00e9ste el lugar de detenernos a rese\u00f1ar el riqu\u00edsimo tesoro documental que guarda su archivo \u2013uno de los m\u00e1s ricos de Toledo\u2013, donde constan las donaciones que los reyes, magnates y gentes sencillas hac\u00edan a las religiosas, ofreciendo lo mejor de sus bienes para el culto divino y para sustento de las mismas. Tampoco queremos entrar a describir la grandeza antigua del edificio, que seg\u00fan Salazar de Mendoza se compon\u00eda de siete claustros, y que todav\u00eda a finales del siglo XVIII fue considerado por el Cardenal Lorenzana como el m\u00e1s apto de Toledo para residencia y educaci\u00f3n de las hijas del Infante Luis de Borb\u00f3n.<\/p>\n\n\n\n<p>Nos contentamos con referimos a algunas figuras insignes representativas de la espiritualidad que se vivi\u00f3 en San Clemente. Las cr\u00f3nicas del Monasterio nos hablan de un espl\u00e9ndido plantel de almas selectas que vivieron santamente su entrega a Dios y ejercieron beneficiosa influencia sobre la Iglesia de Toledo y aun sobre la Iglesia universal.<\/p>\n\n\n\n<p>La primera alma grande de que hay noticia, forjada en San Clemente, es Do\u00f1a Mater, la misma abadesa que ahora hace ocho siglos indujo a sus religiosas a abrazarse con una observancia m\u00e1s estrecha, la del C\u00edster, tal como quiso vivirla San Bernardo: \u00abMujer santa, de singular virtud y exemplo, y hay fama de que en vida obr\u00f3 el Se\u00f1or por ella muchos milagros\u00bb.<\/p>\n\n\n\n<p>Do\u00f1a In\u00e9s Garc\u00eda de Cervatos, nacida en la primera mitad del siglo XV de una ilustre familia toledana, la cual no solamente renunci\u00f3 al mundo y a un brillante porvenir, sino que tambi\u00e9n ofreci\u00f3 para el servicio de Dios todos sus bienes, y, lo que m\u00e1s la ennoblece, dej\u00f3 a la posteridad fama de verdadera santa, seg\u00fan atestiguan un\u00e1nimes los bi\u00f3grafos.<\/p>\n\n\n\n<p>Casi de la misma \u00e9poca es Do\u00f1a Constanza Carrillo, persona \u00abtan regalada de Cristo, que, siempre que comulgaba, quedaba arrobada y transformada en \u00c9l\u00bb. Cuando era abadesa, muchas veces la sorprendieron sus religiosas levantada de la tierra mientras oraba silenciosa ante el Sagrario.<\/p>\n\n\n\n<p>Do\u00f1a Constanza Barroso, natural de Valladolid, \u00abfue una de las mujeres m\u00e1s excelentes que ha tenido San Clemente, y por ventura aquella edad\u00bb. Fue contempor\u00e1nea de Santa Beatriz de Silva y no es improbable que proporcion\u00f3 algunas religiosas para que la Santa ense\u00f1ara las observancias del C\u00edster a las primeras aspirantes a la Orden Concepcionista. Su familiaridad con Cristo era tanta, que, seg\u00fan el P. Francisco Vivar, \u00abcomo otro Job le hablaba cara a cara\u00bb.<\/p>\n\n\n\n<p>Dona Catalina Manrique, de familia distinguida, que vivi\u00f3 y muri\u00f3 como verdadera santa. Falleci\u00f3 en olor de santidad en 1575 y, abierto su sepulcro cuarenta a\u00f1os m\u00e1s tarde, se encontr\u00f3 su cuerpo incorrupto exhalando una fragancia deliciosa.<\/p>\n\n\n\n<p>Do\u00f1a Beatriz de Guzm\u00e1n, priora del Monasterio, amant\u00edsima de la regla y de la penitencia. De ella dice con gracia un cronista que \u00abni el rigor de la penitencia le quit\u00f3 la vida, antes se la aument\u00f3, porque vivi\u00f3 cerca de cien a\u00f1os, creciendo siempre en virtud y perfecci\u00f3n\u00bb.<\/p>\n\n\n\n<p>Do\u00f1a Mar\u00eda Campillo, simple religiosa, que pasaba noches enteras a los pies del Sagrario y, en el hero\u00edsmo de su caridad, ofreci\u00f3 su vida por las almas necesitadas.<\/p>\n\n\n\n<p>Si quisi\u00e9ramos seguir, tendr\u00edamos que hacer la biograf\u00eda de cada una de las religiosas que han vivido en San Clemente, pues la mayor parte de ellas se han esmerado por vivir en plenitud su consagraci\u00f3n a Dios. Pero no es mi fin hacer historia, sino reflexionar sobre esa vida contemplativa, yunque adecuado para la forja de tales almas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Naturaleza de la vida contemplativa<\/h2>\n\n\n\n<p><strong>Santo Tom\u00e1s<\/strong> distingue dos aspectos importantes o clases de vida, activa y contemplativa, seg\u00fan el g\u00e9nero de actividades a que cada cual se dedique. Para \u00e9l, la vida activa se encamina principalmente a las obras exteriores, procura ordenar los movimientos y potencias a hacer el bien, y se entrega a las obras de misericordia con el pr\u00f3jimo, fin nobil\u00edsimo, pero de suyo inferior si se compara con el de la vida contemplativa, que tiene por objeto la contemplaci\u00f3n de la Verdad, del Ser Supremo, de la que nace esa fruici\u00f3n, que constituye la felicidad de los santos<a href=\"#sdfootnote1sym\" id=\"sdfootnote1anc\"><sup>1<\/sup><\/a>.<\/p>\n\n\n\n<p><strong>San Gregorio Magno<\/strong> define las dos vidas casi con id\u00e9nticas ideas, pero empleando distintos t\u00e9rminos. Seg\u00fan \u00e9l, el vivir y el obrar se diferencian entre s\u00ed. La vida activa ejercita la contemplaci\u00f3n de la verdad <em>per modum actus,<\/em> es decir, como algo secundario, mientras las obras exteriores son el blanco principal de sus actividades. La vida contemplativa, en cambio, tiene las obras exteriores como algo accidental, no se detiene en ellas, porque pone su af\u00e1n en la contemplaci\u00f3n y fruici\u00f3n de la verdad que la absorbe. O sea, si por un imperativo del deber o la necesidad se viera el alma contemplativa obligada a ocuparse en obras de apostolado externo, con todo, su deseo interno es dejar cuanto antes todo lo que distrae para vacar sin estorbos al objeto que llena su vida, la contemplaci\u00f3n del Sumo Bien<a href=\"#sdfootnote2sym\" id=\"sdfootnote2anc\"><sup>2<\/sup><\/a>.<\/p>\n\n\n\n<p><strong>San Bernardo<\/strong>, el gran contemplativo y maestro de contemplativos, define la contemplaci\u00f3n como \u00abuna intuici\u00f3n verdadera y cierta que tiene el alma de cualquier objeto, y como el acto por el cual el esp\u00edritu se adhiere a una verdad de un modo indubitable\u00bb<a href=\"#sdfootnote3sym\" id=\"sdfootnote3anc\"><sup>3<\/sup><\/a>.<\/p>\n\n\n\n<p>El santo fija la contemplaci\u00f3n no s\u00f3lo en la intuici\u00f3n de la verdad, antes va m\u00e1s lejos, se\u00f1alando el objeto de la misma: <em>disfrutar el objeto que se intuye,<\/em> aprehender, adherirse a la verdad que contempla el entendimiento para adquirir m\u00e1s conocimiento del objeto amado, a fin de que cuanto m\u00e1s se le conozca m\u00e1s se le ame.<\/p>\n\n\n\n<p>\u00abEste trabajo \u2013a\u00f1ade el santo\u2013 nunca puede ser fruto de la voluntad humana, sino que proviene del benepl\u00e1cito divino\u00bb; es una gracia especial de Dios.<\/p>\n\n\n\n<p>Para el <strong>Cardenal Bona<\/strong>, \u00abcontemplaci\u00f3n es una funci\u00f3n propia de los m\u00edsticos y la parte m\u00e1s destacada de la vida humana, la cual tiene por fin y objeto al mismo Dios, y que, al decir de Santo Tom\u00e1s, consiste en cierta visi\u00f3n suave, reposada y amable de la verdad eterna, la cual mira sinceramente sin variedad de relaciones, y penetra con gran amor y admiraci\u00f3n, con tanta certeza y claridad, que se considera visi\u00f3n de Dios cara a cara, seg\u00fan expresi\u00f3n de la Sagrada Escritura. Mas no como los bienaventurados en la gloria, sino con menor luz. entre celajes y apoyados en la fe, que es perfeccionada y esclarecida por \u00c9l. De este conocimiento se inflama el amor y, al mismo tiempo, crece el conocimiento a impulsos del mismo amor. Pues el amor es fuego ardiente y luciente: ardiente en la voluntad, iluminante del entendimiento que nos impulsa a fijar los ojos all\u00ed donde est\u00e1 nuestro tesoro, el que ama nuestro coraz\u00f3n, cuya bondad y hermosura, inmensa e infinita, excita m\u00e1s y m\u00e1s las ansias de nuestro coraz\u00f3n en el amor y deseo de contemplarle con mayor perfecci\u00f3n\u00bb<a href=\"#sdfootnote4sym\" id=\"sdfootnote4anc\"><sup>4<\/sup><\/a>.<\/p>\n\n\n\n<p>Un autor de nuestros d\u00edas sintetiza en breves frases la dimensi\u00f3n contemplativa cuando la describe como \u00abuna b\u00fasqueda sincera de Dios por medio del conocimiento y el amor\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Elementos constitutivos<\/h2>\n\n\n\n<p>Podemos distinguir seis: tres que pudi\u00e9ramos llamar negativos, porque si no se observan no puede darse la verdadera contemplaci\u00f3n, y otros tres positivos, que llevan de la mano al alma a sumergirse en la contemplaci\u00f3n del Sumo Bien.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Elementos negativos<\/h3>\n\n\n\n<p><strong>1.<\/strong> En primer lugar, la <em><strong>soledad<\/strong><\/em><em>,<\/em> a la que hace referencia incluso la etimolog\u00eda de la palabra monje, \u00abmonach\u00f3s\u00bb, solitario, hombre segregado de la sociedad, separado del mundo. La soledad es condici\u00f3n indispensable para llegar a la contemplaci\u00f3n, por cuanto <em>non in conmotione Dominus,<\/em> el Se\u00f1or no se halla en medio del bullicio y de la agitaci\u00f3n. Cuando Dios quiere atraer a S\u00ed un alma, la lleva a la soledad y all\u00ed le habla al coraz\u00f3n. \u00abNo puede ser monje \u2013escrib\u00eda un solitario\u2013 el que gusta de frecuentar los lugares concurridos por la multitud. Quien se complace en visitar las ciudades, no gustar\u00e1 las delicias de la vida mon\u00e1stica\u00bb<a href=\"#sdfootnote5sym\" id=\"sdfootnote5anc\"><sup>5<\/sup><\/a>.<\/p>\n\n\n\n<p>Las excelencias de la soledad fueron cantadas en todos los tonos por poetas y santos. Fr. Luis de Le\u00f3n se inundaba de gozo cuando ponderaba las bellezas del monte solitario, del r\u00edo que discurre en calma interrumpida \u00fanicamente por el alegre trinar de los pajarillos. Lope de Vega no encontraba mejor compa\u00f1\u00eda, al ir y venir de sus soledades, que sus propios pensamientos.<\/p>\n\n\n\n<p>San Juan de la Cruz, cuyo coraz\u00f3n se inflamaba en amor divino cuando recordaba con nostalgia la soledad tranquila y apacible, prorrumpi\u00f3 en aqu\u00e9l su canto espiritual:<\/p>\n\n\n\n<p>\u00abEn soledad viv\u00eda,<br>y en soledad ha puesto ya su nido,<br>y en soledad la gu\u00eda<br>a solas su querido,<br>tambi\u00e9n en soledad de amor herido.\u00bb<\/p>\n\n\n\n<p><strong>2.<\/strong> El segundo elemento favorable a la vida contemplativa es la <em><strong>clausura<\/strong><\/em><em>.<\/em><\/p>\n\n\n\n<p>El contemplativo ha de ser, s\u00ed, el hombre del desierto, de la monta\u00f1a solitaria. Debe tener suspendida su morada en un picacho rocoso, entre el cielo y la tierra, como un puente que une a la humanidad con Dios, y anuncia la ruta que a Dios conduce. Para ello debe vivir alejado del mundo con el cuerpo y con el esp\u00edritu. Porque de nada servir\u00eda haber huido del mundo, si \u00e9ste se introdujera f\u00e1cilmente en el retiro del claustro; de nada servir\u00eda vivir en soledad si \u00e9sta fuera profanada por el ruido mundano.<\/p>\n\n\n\n<p>La clausura debe ser para el alma contemplativa lo que es el agua para el pez, su propio ambiente: si sale del agua, perece sin remedio. La clausura es como el seto protector de los jardines: si se quita esa defensa, al punto las flores son aplastadas.<\/p>\n\n\n\n<p>San Juan Cris\u00f3stomo tiene una p\u00e1gina maravillosa acerca del esp\u00edritu reinante en los primeros monjes del yermo, alejados del mundo para vivir mejor la intimidad de Dios. \u00abHan huido de las plazas p\u00fablicas \u2013escribe el santo\u2013, de las ciudades y tumulto del siglo, han establecido su morada en las concavidades de las monta\u00f1as para llevar una vida que nada tiene que ver con el mundo&#8230; All\u00ed en los bosques, junto a las deliciosas corrientes, sobre las alturas que les proporcionan una calma completa, se ocupan en meditar acerca de las cosas divinas, y, sobre todo, en comunicarse con Dios por la oraci\u00f3n. Su celda desconoce el ruido, su alma est\u00e1 libre de toda pasi\u00f3n, es m\u00e1s pura que el aire transparente\u00bb<a href=\"#sdfootnote6sym\" id=\"sdfootnote6anc\"><sup>6<\/sup><\/a>.<\/p>\n\n\n\n<p>Los Santos han visto un doble peligro de muerte para la clausura: la irrupci\u00f3n del mundo en los claustros, con sus pensamientos y su modo de obrar en pugna con el Evangelio, y la excesiva frecuentaci\u00f3n del mundo por parte de los religiosos. Por eso recomendaron con toda el alma huir de tales escollos, para mantener el esp\u00edritu y el coraz\u00f3n alejado de todo trato mundano.<\/p>\n\n\n\n<p>Hoy habr\u00eda que insistir, tal vez, dando la voz de alerta sobre este punto, cuando vemos que el mundo ataca con mayor violencia a los monasterios de clausura, tratando de derribar el muro de separaci\u00f3n para as\u00ed penetrar mejor en ellos con sus m\u00e1ximas enteramente opuestas a las de Cristo. Es un error pensar que mitigando la santa clausura van a afluir mayor n\u00famero de vocaciones. Todo lo contrario. Estas son fruto espl\u00e9ndido de la gracia, hechura de Dios, el cual las enviar\u00e1 a las comunidades en la medida en que se mantengan fieles a las observaciones establecidas por los fundadores.<\/p>\n\n\n\n<p><strong>3.<\/strong> Tambi\u00e9n el <em><strong>silencio<\/strong><\/em> contribuye de manera positiva a fomentar una vida de aut\u00e9ntica contemplaci\u00f3n. De nada servir\u00eda, en efecto, haber abandonado el mundo y haberse encerrado dentro de los muros de un claustro, si en \u00e9l reina un ambiente de disipaci\u00f3n. Sin la virtud del silencio peligra el aut\u00e9ntico esp\u00edritu religioso. En la Sagrada Escritura hallamos infinidad de testimonios que vienen a confirmarlo: <em>Si alguno cree que es religioso y no refrena su lengua, se enga\u00f1a, su religi\u00f3n es vana<\/em> (St 1, 26). <em>El que abusa de las palabras, da\u00f1ar\u00e1 su alma <\/em>(Eclo 20, 8). <em>El que no se puede contener en el hablar, es como una ciudad abierta, sin defensa y sin muros<\/em> (Prv 25, 8).<\/p>\n\n\n\n<p>Mas no basta la observancia de un silencio exterior si no va unido al interior, es decir, al recogimiento, a la guarda de los sentidos, a refrenar la imaginaci\u00f3n. Solamente cuando reine el silencio en el interior, cuando las pasiones est\u00e9n sometidas al esp\u00edritu, ser\u00e1 cuando se pueda o\u00edr la suavidad de la voz divina que habla con su lenguaje innegable.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Elementos positivos<\/h3>\n\n\n\n<p>Para llegar a ser almas contemplativas aut\u00e9nticas no s\u00f3lo es preciso remover obst\u00e1culos, sino tambi\u00e9n hacer actos positivos encaminados a la consecuci\u00f3n de tan noble ideal. Apuntaremos solamente tres que ayudan eficazmente a lograr un conocimiento profundo y sabroso de Dios, y a vivir unidos a \u00c9l y sumergidos en su voluntad sant\u00edsima.<\/p>\n\n\n\n<p><strong>1.<\/strong> Uno es la <em><strong>lectura espiritual<\/strong><\/em> seria, reposada, constante. Es alimento del alma, antorcha que ilumina el sendero de la vida para llevarnos al conocimiento y amor de Dios. El testimonio de los Santos es un\u00e1nime en esta materia: \u00abMedita d\u00eda y noche en las Sagradas Escrituras, de suerte que te sorprenda el sue\u00f1o con el libro en la mano, y si os cayereis dormido, sea sobre la p\u00e1gina que estabais leyendo\u00bb<a href=\"#sdfootnote7sym\" id=\"sdfootnote7anc\"><sup>7<\/sup><\/a>. \u00abMis delicias m\u00e1s castas y puras est\u00e1n, Se\u00f1or, en la lectura de las Sagradas Escrituras\u00bb<a href=\"#sdfootnote8sym\" id=\"sdfootnote8anc\"><sup>8<\/sup><\/a>. \u00abIgnorar las Escrituras es desconocer a Cristo\u00bb<a href=\"#sdfootnote9sym\" id=\"sdfootnote9anc\"><sup>9<\/sup><\/a>. \u00abLa fuente de la contemplaci\u00f3n m\u00e1s pura y fecunda es la Sagrada Escritura, porque la contemplaci\u00f3n es el movimiento del alma, que tocada e iluminada de los rayos divinos, penetra los divinos misterios\u00bb<a href=\"#sdfootnote10sym\" id=\"sdfootnote10anc\"><sup>10<\/sup><\/a>.<\/p>\n\n\n\n<p>Toda alma dedicada a la vida espiritual que no sienta gran atractivo por la lectura espiritual y no se entregue a ella con gran asiduidad est\u00e1 en peligro, si no de caer en la tibieza, s\u00ed de llevar en el Monasterio una vida fr\u00edvola y sin sentido.<\/p>\n\n\n\n<p>Adem\u00e1s de la Sagrada Escritura, las obras de los Santos Padres, las de los autores asc\u00e9ticos y m\u00edsticos recomendados por la Iglesia, las vidas de los Santos, los documentos principales del Magisterio eclesi\u00e1stico deben encontrar asiduos y fervorosos lectores en las comunidades mon\u00e1sticas.<\/p>\n\n\n\n<p><strong>2.<\/strong> En segundo lugar, est\u00e1 la<em><strong>oraci\u00f3n lit\u00fargica<\/strong><\/em><em>,<\/em> o el Oficio Divino. Alabar a Dios, bendecirle en su infinita grandeza, y esto en nombre de la humanidad entera, es la ocupaci\u00f3n favorita de las almas contemplativas. El Oficio Divino da una gloria inmensa a Dios, es un lenguaje que pone en contacto con el cielo, con Dios en su inefable misterio trinitario, con la Sant\u00edsima Virgen, con los Santos.<\/p>\n\n\n\n<p>Es en la oraci\u00f3n lit\u00fargica donde el alma contemplativa robustece su piedad, se comunica con el Padre y ejerce una irradiaci\u00f3n ben\u00e9fica sobre toda la Iglesia. Para las almas contemplativas, conscientes del valor inmenso de la vida lit\u00fargica, del fruto misterioso encerrado en ella, nada hay m\u00e1s querido como este entonar d\u00eda y noche las divinas alabanzas. En ellas encuentran a diario alimento copioso y un raudal abundante de aguas saludables donde apagar su sed ardiente y mitigar la de sus hermanos los hombres. Por eso el alma contemplativa acude ansiosa al rezo del Oficio, como el ciervo sediento a las fuentes de las aguas.<\/p>\n\n\n\n<p><strong>3. <\/strong>Dejamos para el final el tercer medio positivo encaminado a fomentar la contemplaci\u00f3n, no por ser inferior, sino porque es como el compendio, el lazo de uni\u00f3n, la s\u00edntesis de todo lo dem\u00e1s que pudi\u00e9ramos ofrecer. Nos referimos a la <em><strong>oraci\u00f3n mental<\/strong><\/em><em>,<\/em> en la que se desenvuelve el alma como los seres vivos en la atm\u00f3sfera oxigenada y pura. Del mismo modo que cuando \u00e9sta falta se hacen imposibles la respiraci\u00f3n y la vida, as\u00ed tambi\u00e9n, sin oraci\u00f3n, no puede haber vida sobrenatural ni verdadera contemplaci\u00f3n.<\/p>\n\n\n\n<p>Oraci\u00f3n es una conversaci\u00f3n \u00edntima, suave, placentera con Dios, una elevaci\u00f3n del alma sobre todo lo terreno a la contemplaci\u00f3n del Ser Supremo, es pedirle gracias para s\u00ed, para sus hermanos, para todo el mundo. Es recrearse en las perfecciones divinas y vivir sumergidos en Dios. Es elegir \u00abla mejor parte\u00bb, que nunca ser\u00e1 arrebatada; es una pregustaci\u00f3n de la felicidad eterna. \u00abLa oraci\u00f3n es una conversaci\u00f3n de coraz\u00f3n a coraz\u00f3n, un comercio de amistad en el que el alma se une amorosamente a Dios\u00bb. Nada purifica tanto como el duro crisol de la noche oscura, nada impulsa tanto a las cumbres de la perfecci\u00f3n como los ardores de una sabrosa contemplaci\u00f3n.<\/p>\n\n\n\n<p>A medida que el alma se vac\u00eda de s\u00ed misma. Dios la encuentra m\u00e1s dispuesta para obrar en ella los grandes misterios que ha tenido con sus \u00edntimos amadores y la une a S\u00ed con fuerte abrazo. El metal sumergido en el fuego bien pronto adquiere las propiedades de \u00e9ste; de la misma manera, el alma que a trav\u00e9s de la oraci\u00f3n se sumerge en Dios, horno ardent\u00edsimo de caridad, se inunda de luz y de calor, se inflama en vivos ardores que luego cristalizan en ansias de entrega a \u00c9l, a su voluntad sant\u00edsima, a desear que sea amado de todos los hombres.<\/p>\n\n\n\n<p>Se explica que el inmortal P\u00edo XII, en el ocaso de su vida \u2013agosto de 1958\u2013, al dirigirse a las religiosas contemplativas, colocara la oraci\u00f3n como fundamento b\u00e1sico de la contemplaci\u00f3n: \u00abOs exhortamos \u2013les dec\u00eda\u2013 a consagraros de todo coraz\u00f3n a la oraci\u00f3n contemplativa, que es vuestra tarea <em>esencial\u00bb.<\/em> O sea, nunca podr\u00e9is llegar a ser almas contemplativas como quiere y espera la Iglesia si no sois almas de oraci\u00f3n ardiente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fecundidad de la vida contemplativa<\/h2>\n\n\n\n<p>En el \u00faltimo serm\u00f3n a sus disc\u00edpulos, Jesucristo traz\u00f3 en breves rasgos las leyes de un apostolado fecundo: <em>Yo soy la vid, vosotros los sarmientos. El que permanece en M\u00ed y Yo en \u00e9l dar\u00e1 mucho fruto, porque sin M\u00ed nada pod\u00e9is hacer&#8230; Si permanec\u00e9is en M\u00ed y mis palabras permanecen en vosotros, pedir\u00e9is lo que quisiereis y se os otorgar\u00e1&#8230; Perseverad en mi amor<\/em> (Jn 15, 5-10). En estas breves palabras est\u00e1 sintetizada la ra\u00edz del verdadero apostolado cristiano, que no consiste sino en comunicar Dios al mundo, lo cual solamente se podr\u00e1 hacer en la medida en que el sarmiento permanezca m\u00e1s o menos unido a la vid. Cuanto m\u00e1s unidos, m\u00e1s eficacia en el apostolado, y cuanta menos uni\u00f3n, menos influencia en las almas, y hasta se puede dar el caso de un apostolado nulo si no existe la uni\u00f3n necesaria con la vid.<\/p>\n\n\n\n<p>\u00abEs propio de la verdadera y pura contemplaci\u00f3n \u2013 escribe San Bernardo\u2013 que el alma, abrasada en el fuego divino, se inflame en celo ardiente y en deseos vehementes de dar a Dios corazones que le amen\u00bb<a href=\"#sdfootnote11sym\" id=\"sdfootnote11anc\"><sup>11<\/sup><\/a>. Efectivamente, no hay posibilidad de contemplaci\u00f3n sin sentir arder el alma en un amor entra\u00f1able a Cristo y a cuanto \u00c9l ama, ni se puede dar el amor de Cristo si no se tiene sed ardent\u00edsima de la salvaci\u00f3n de las almas, por las cuales derram\u00f3 su sangre preciosa.<\/p>\n\n\n\n<p>El apostolado viene a ser como un fruto que brota de la flor de la contemplaci\u00f3n, y cuanto m\u00e1s contemplativa sea el alma, m\u00e1s fuerza de irradiaci\u00f3n ejercer\u00e1 en derredor suyo. Pues aun cuando la misi\u00f3n del alma contemplativa no tiene por fin el apostolado externo, sin embargo, la fidelidad a Dios, la entrega absoluta a su voluntad, la constancia en el cumplimiento del deber son como el venero fecundo de donde brotan las fuerzas m\u00e1s eficaces para el apostolado que realiza la Iglesia, aunque de una manera oculta y s\u00f3lo perceptible a los ojos divinos.<\/p>\n\n\n\n<p>La vida contemplativa es como el dep\u00f3sito escondido en el coraz\u00f3n de la monta\u00f1a que alimenta sin cesar el surtidor de agua cristalina que fertiliza la tierra: nadie ve aquel manantial oculto, mas su influencia es decisiva para la productividad de la tierra y para satisfacer las necesidades del hombre.<\/p>\n\n\n\n<p>El mundo de hoy acostumbra a medir el valor de las personas con el rasero de los frutos visibles que aportan a la sociedad. En este sentido habr\u00eda que pensar que los treinta primeros a\u00f1os de la vida del Se\u00f1or no sirvieron para nada. Error funesto. Estos a\u00f1os de Jes\u00fas ejercieron en las almas la misma influencia santificadora que los dedicados a la vida activa. Su intensa y continua oraci\u00f3n, unida al sacrificio de cada d\u00eda, fueron raudales de gracia que inundaron el mundo y le prepararon a la siembra de la semilla evang\u00e9lica.<\/p>\n\n\n\n<p>Tambi\u00e9n la Sant\u00edsima Virgen fue la gran contemplativa que pas\u00f3 su vida oculta, sin aparecer en p\u00fablico, dedicada a guardar en su coraz\u00f3n pur\u00edsimo las palabras brotadas de labios de su divino Hijo. La oraci\u00f3n y el sacrificio de su existencia no pudieron menos de atraer torrentes de gracias sobre las almas. Nadie habr\u00e1 que se atreva a negar el fecundo apostolado de una vida toda de Dios, consumida en el silencio y en la oraci\u00f3n.<\/p>\n\n\n\n<p>San Jos\u00e9 sigui\u00f3 igualmente las huellas de la Sant\u00edsima Virgen, llevando intensa vida de contemplativo. Jam\u00e1s apareci\u00f3 en p\u00fablico para ejercer ministerio alguno, cuando tanta necesidad hab\u00eda de predicaci\u00f3n, antes vivi\u00f3 oculto en el anonimato, trabajando intensamente en la obra que le confiara el Padre, sin escatimar sacrificio alguno, ofreciendo todo con coraz\u00f3n generoso y enamorado de Dios en beneficio de las almas.<\/p>\n\n\n\n<p>Estos modelos son suficientes para explicar la fecundidad de la vida contemplativa, tambi\u00e9n en apariencia in\u00fatil, pero a los ojos de Dios de una transcendencia incomparable.<\/p>\n\n\n\n<p>Dios comunica al alma interior una fecundidad misteriosa. Rica en Dios por las gracias superabundantes que la inundan, procura difundir el bien atesorado entre los m\u00e1s necesitados. De aqu\u00ed nace aquella maternidad espiritual de la que habla San Bernardo cuando distingu\u00eda dos clases de alumbramiento, o sea, dos clases de hijos, y una doble maternidad espiritual \u2013no contrarias entre s\u00ed\u2013: la que los engendra para Dios y los da a luz con la actividad de la predicaci\u00f3n, y la que los engendra y da a luz a trav\u00e9s de la contemplaci\u00f3n.<\/p>\n\n\n\n<p>Este segundo alumbramiento, propio de las almas contemplativas, es para el santo, el m\u00e1s atractivo y fecundo, pues es como llegar a olvidarse de s\u00ed para darse a las almas, para que, mediante su amor a Dios y uni\u00f3n con \u00c9l, aumente prodigiosamente el n\u00famero de los hijos de la Iglesia<a href=\"#sdfootnote12sym\" id=\"sdfootnote12anc\"><sup>12<\/sup><\/a>.<\/p>\n\n\n\n<p>Esta maternidad espiritual, esta fecundidad ardiente en la comunicaci\u00f3n de la vida divina a las almas, la sintieron muy hondo los santos y todos aquellos que de alg\u00fan modo se distinguieron por sus virtudes extraordinarias. De ah\u00ed la inmolaci\u00f3n silenciosa de multitud de vidas ejemplares en el seno de los claustros. Sirva de ejemplo <strong>Sor Isabel de la Sant\u00edsima Trinidad<\/strong>, la carmelita que escal\u00f3 las cumbres de la santidad viviendo el dogma consolador de la inhabitaci\u00f3n de la Sant\u00edsima Trinidad en el alma del justo, cuya doctrina est\u00e1 ejerciendo un ben\u00e9fico influjo en la Santa Iglesia. Tambi\u00e9n ella sent\u00eda, como esposa enamorada de Cristo, ansias de llevarle almas, de alimentar a tantos hijos hambrientos como discurren por el mundo sin conocer ni amar a Dios. Fue una antorcha que no solamente alumbraba, sino tambi\u00e9n calentaba los corazones con el fuego de su oraci\u00f3n abrasada en amores divinos.<\/p>\n\n\n\n<p>Por su doctrina y por su riqu\u00edsima vida interior es presentada como asociada al sacerdote en su apostolado. Por eso, \u00abmientras el sacerdote lleva a Cristo a las almas por la palabra, los sacramentos y las otras formas variadas de su ministerio, la Carmelita, silenciosamente, se queda como Magdalena a los pies de Cristo, o mejor, como la Virgen Corredentora junto a la Cruz, identificada interiormente con todos los movimientos del alma del crucificado, y muriendo con \u00c9l por los mismos fines redentores\u00bb<a href=\"#sdfootnote13sym\" id=\"sdfootnote13anc\"><sup>13<\/sup><\/a>.<\/p>\n\n\n\n<p>Otro ejemplo m\u00e1s reciente. En 1935, poco antes de reingresar en la Trapa, <strong>Fray M\u00aa Rafael<\/strong> oy\u00f3 un serm\u00f3n que le desconcert\u00f3 en sumo grado: \u00abAyer, al llegar a la iglesia \u2013escribe este joven\u2013 a\u00fan no se hab\u00eda acabado el serm\u00f3n; era un Padre que yo conozco mucho, y dijo unas cosas que me dejaron un poco&#8230;, no s\u00e9 c\u00f3mo&#8230;; estaba hablando de la vida activa y del consuelo de ser ap\u00f3stol y presentarse un d\u00eda delante de Dios con todas las almas que hab\u00eda ayudado; dijo no s\u00e9 qu\u00e9 de esos esp\u00edritus ego\u00edstas que no quieren m\u00e1s que su santificaci\u00f3n y que se ocultan a las miradas de los hombres para no ser molestados&#8230;; dijo cosas, y a m\u00ed me hizo pensar&#8230;; no me gust\u00f3 lo que dijo&#8230;, sin saber por qu\u00e9 me inquiet\u00f3 un poco\u00bb.<\/p>\n\n\n\n<p>Explica a continuaci\u00f3n el motivo de su inquietud, o mejor, su desconformidad con aquella doctrina: \u00abPero, Se\u00f1or, si es que no puedo&#8230;; si es que si me distraigo con los hombres, pierdo de estar con Dios&#8230;; si yo no quiero m\u00e1s que amar&#8230;; \u00bfpor qu\u00e9 no me dejan?, \u00bfhago acaso mal?&#8230;; seg\u00fan este Padre, s\u00ed; seg\u00fan \u00e9l, no dan gloria a Dios m\u00e1s que los que se ocupan, como Marta&#8230;; \u00bfestar\u00e9 yo equivocado?, \u00bfser\u00e9 ego\u00edsta?&#8230; Se\u00f1or, Se\u00f1or&#8230;, ilumina mi raz\u00f3n&#8230;; la contradicci\u00f3n me aprieta por todos lados&#8230;; el que es del mundo me llama loco, y el que es de Dios, tambi\u00e9n, aunque de otra manera&#8230;\u00bb.<\/p>\n\n\n\n<p>\u00bfQu\u00e9 hubiera sucedido si este joven, con excelentes cualidades de ap\u00f3stol, en vez de seguir su vocaci\u00f3n a la Trapa, hubiera hecho caso del predicador y se hubiera lanzado a la vida activa? Sin duda no habr\u00eda perdido el tiempo; pero quiz\u00e1 consigui\u00f3 mucho m\u00e1s con su vida de oraci\u00f3n y entrega total a Dios, exigencia de su coraz\u00f3n movido por la gracia, seg\u00fan se deduce de estos pensamientos: \u00abQuisiera volar por el mundo gritando a sus moradores: \u00a1Dios, Dios y s\u00f3lo \u00c9l!&#8230; \u00bfQu\u00e9 busc\u00e1is? \u00bfQu\u00e9 mir\u00e1is? \u00a1Pobre mundo dormido que no conoce las maravillas de Dios! Mi vocaci\u00f3n es sufrir, sufrir en silencio por el mundo entero, inmolarme junto a Jes\u00fas por los pecados de mis hermanos, los sacerdotes, los misioneros, por las necesidades de la Iglesia, por los pecados del mundo&#8230;\u00bb<a href=\"#sdfootnote14sym\" id=\"sdfootnote14anc\"><sup>14<\/sup><\/a>.<\/p>\n\n\n\n<p>Indudablemente hacen falta misioneros, predicadores de la palabra de Dios, directores de almas, pues <em>la mies es mucha y los operarios pocos,<\/em> pero hoy d\u00eda quiz\u00e1 lo que m\u00e1s se necesite en el mundo sean imitadores de la vida oculta del Se\u00f1or, hombres y mujeres de verdadera entrega a la oraci\u00f3n y al sacrificio, almas viviendo en el claustro una espiritualidad total.<\/p>\n\n\n\n<p>Maravilloso es el apostolado que desde esos centros de irradiaci\u00f3n espiritual se puede desarrollar mediante la oraci\u00f3n y una vida de sacrificio. \u00abSi no se rogara, dice el venerable P. Eymard, si no hubiera almas que se inmolaran en uni\u00f3n con nuestro Se\u00f1or a favor de los pecadores, la voz de los misioneros no ser\u00eda otra cosa que metal que suena o campana que reti\u00f1e\u00bb. \u00abLas Ordenes mon\u00e1sticas consagradas a la contemplaci\u00f3n, a la alabanza, a la penitencia son la parte m\u00e1s preciosa y tambi\u00e9n m\u00e1s oculta de la Iglesia. Son en medio del mundo, el anticipo, la incoaci\u00f3n de la Jerusal\u00e9n celeste. El papel del monje es tener abierta la puerta del cielo por donde la Iglesia participa en la liturgia celeste, que es su raz\u00f3n \u00faltima. El monje se coloca, por lo mismo, en la vanguardia del gran retomo de la humanidad redimida\u00bb<a href=\"#sdfootnote15sym\" id=\"sdfootnote15anc\"><sup>15<\/sup><\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La vida contemplativa en la hora actual<\/h2>\n\n\n\n<p>No es ning\u00fan secreto afirmar que estamos atravesando una de las m\u00e1s hondas crisis que ha conocido la historia. Yo dir\u00eda que nos hallamos en el punto medio entre dos eras, una que se despide pugnando por mantener firmes sus normas, sus tradiciones seculares, y otra que quiere abrirse paso a toda costa, renovando estructuras, cambiando costumbres y hasta, en algunos sectores, intentando poner en duda los dogmas m\u00e1s fundamentales.<\/p>\n\n\n\n<p>El choque entre ambas es brusco, desconcertante y est\u00e1 llevando la inquietud y la desorientaci\u00f3n a multitud de almas. Puede llegar hasta vosotras, y de hecho ha llegado. Algunas religiosas, menos ciertamente que en otras instituciones, despu\u00e9s de a\u00f1os de consagraci\u00f3n a Dios, se han dejado llevar de las nuevas orientaciones, rompiendo los m\u00e1s solemnes compromisos, no con mal fin, sino enga\u00f1adas por falsas doctrinas.<\/p>\n\n\n\n<p>Para renovar vuestro entusiasmo por el g\u00e9nero de vida a que est\u00e1is consagradas quiero ofreceros un poco de luz sobre lo que ha pensado la Iglesia de la vida contemplativa antes del Concilio, lo que piensa en el momento actual, y cu\u00e1l debe ser vuestra respuesta a las esperanzas de esa misma Iglesia que tanto os ama.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Antes del Concilio<\/h3>\n\n\n\n<p>Ser\u00eda necesario examinar toda la literatura patr\u00edstica, los escritores asc\u00e9ticos y el magisterio ordinario de los Sumos Pont\u00edfices. Forma todo ello un canto sublime a la vida de consagraci\u00f3n total a Dios, lejos del mundo. Pero no es posible hacerlo. S\u00f3lo aduciremos algunos textos de los \u00faltimos Papas.<\/p>\n\n\n\n<p><strong>San P\u00edo X<\/strong>, en su carta a una Superiora de la Visitaci\u00f3n, le dec\u00eda en 1909: \u00abVosotras hab\u00e9is escogido la mejor parte, no la abandon\u00e9is, y no os dej\u00e9is apartar por nada del mundo de vuestra santa resoluci\u00f3n, bajo pretexto de querer ir a trabajar por la salvaci\u00f3n del pr\u00f3jimo, siguiendo la falsa idea de que estos tiempos revueltos exigen vidas dedicadas a la acci\u00f3n, no a la contemplaci\u00f3n\u00bb.<\/p>\n\n\n\n<p>\u00abLos contemplativos \u2013escrib\u00eda <strong>P\u00edo XI<\/strong> a los PP. Cartujos\u2013 se entregan a una especie de apostolado oculto y silencioso&#8230; Deseamos que tan valiosa instituci\u00f3n se extienda y aumente. Pero si alguna vez fue necesario que hubiese anacoretas de esta clase en la Iglesia de Dios, es especialmente oportuno hoy en d\u00eda, cuando vemos a tantos cristianos&#8230; dando rienda a su af\u00e1n por las riquezas terrenas y los placeres de la carne&#8230; Pero es f\u00e1cil de comprender c\u00f3mo aquellos que asiduamente cumplen con el deber de la oraci\u00f3n y la penitencia contribuyen mucho m\u00e1s al incremento de la Iglesia y al bienestar de la humanidad, que aquellos que trabajan cultivando el campo del Maestro\u00bb<a href=\"#sdfootnote16sym\" id=\"sdfootnote16anc\"><sup>16<\/sup><\/a>.<\/p>\n\n\n\n<p>El mismo inmortal Pont\u00edfice, en la enc\u00edclica <em>Divini Redemptoris, <\/em>dirigida al mundo para dar la voz de alerta contra el comunismo ateo que ya entonces pretend\u00eda apoderarse de Europa, previendo los males que de ese hecho podr\u00edan derivarse a la Iglesia, dec\u00eda: \u00abTampoco podr\u00e1 ser vencido el mal que hoy atormenta a la humanidad, sino con una santa y universal cruzada de oraci\u00f3n y penitencia; y recomendamos singularmente a las \u00d3rdenes contemplativas, masculinas y femeninas, que redoblen sus s\u00faplicas y sacrificios para impetrar del cielo una poderosa ayuda a la Iglesia en las luchas presentes, con la poderosa intercesi\u00f3n de la Virgen Inmaculada, la cual as\u00ed como un d\u00eda aplast\u00f3 la cabeza de la serpiente antigua, as\u00ed tambi\u00e9n es hoy segura defensa e invencible Auxilio de los cristianos\u00bb<a href=\"#sdfootnote17sym\" id=\"sdfootnote17anc\"><sup>17<\/sup><\/a>.<\/p>\n\n\n\n<p><strong>P\u00edo XII<\/strong> demostr\u00f3 siempre una gran predilecci\u00f3n por las almas consagradas a Dios en el retiro del claustro, alejadas del mundo. Bien lo manifest\u00f3 en aquel tr\u00edptico de Radiomensajes dirigidos a las Religiosas de clausura, en el verano de 1958. Era la primera vez que un Papa se dirig\u00eda directamente a las almas contemplativas, dej\u00e1ndoles como testamento espiritual las mejores alabanzas tributadas a la vida de consagraci\u00f3n a Dios. \u00abLos que llevan vida contemplativa, dec\u00eda el Papa, concurren con suma eficacia al bien de la Iglesia, precisamente porque ofrecen a Dios, por la salvaci\u00f3n de los dem\u00e1s, no s\u00f3lo sus preces y s\u00faplicas, sino aun su propia inmolaci\u00f3n personal\u00bb.<\/p>\n\n\n\n<p>Luego, saliendo al paso de algunas corrientes imperantes, ya en aquella \u00e9poca, de desestima de la vida contemplativa, aun en sacerdotes y alg\u00fan prelado, escrib\u00eda: \u00abEst\u00e1n fuera de la verdad quienes piensan que los Institutos religiosos antiguos carecen de utilidad en los tiempos presentes&#8230; Sois vosotras, en la Iglesia, esas escuelas de santidad oficialmente reconocidas. Donde ellas faltan, la vida cristiana no tiene ni puede tener aquella pujanza que es caracter\u00edstica del Cuerpo M\u00edstico en su estado actual de desenvolvimiento. Es hacia los estados de perfecci\u00f3n hacia donde ella, sobre todo, se orienta, expande y manifiesta\u00bb<a href=\"#sdfootnote18sym\" id=\"sdfootnote18anc\"><sup>18<\/sup><\/a>.<\/p>\n\n\n\n<p><strong>Juan XXIII<\/strong> declar\u00f3 a la faz del mundo la importancia de la vida de consagraci\u00f3n total a Dios. Eran tiempos de intensa preparaci\u00f3n del Vaticano II, y muchos cre\u00edan que hab\u00eda llegado el momento, dando de lado a la contemplaci\u00f3n, de que religiosos y religiosas salieran al mundo para lanzarse al apostolado y dar testimonio de Cristo. El pont\u00edfice se encarg\u00f3 de desvanecer tales ideas con aquella memorable alocuci\u00f3n precisamente a los Abades del C\u00edster de la Estrecha Observancia: \u00abAunque la Iglesia urja tan fuertemente el apostolado externo, tan necesario en nuestros d\u00edas, sin embargo, atribuye la mayor importancia a la contemplaci\u00f3n, y esto muy especialmente en nuestra \u00e9poca en que se insiste demasiado en la acci\u00f3n exterior. Efectivamente, el aut\u00e9ntico apostolado consiste precisamente en participar en la obra de salvaci\u00f3n de Cristo. Ahora bien, esta participaci\u00f3n es imposible sin un intenso esp\u00edritu de oraci\u00f3n y sacrificio. Cristo rescat\u00f3 al mundo esclavo del pecado, principalmente por su oraci\u00f3n y sacrific\u00e1ndose a s\u00ed mismo. Por eso, las almas que se esfuerzan por revivir este aspecto \u00edntimo de la misi\u00f3n de Cristo, aunque no se consagren a ninguna actividad exterior, practican el apostolado de una manera eminente\u00bb<a href=\"#sdfootnote19sym\" id=\"sdfootnote19anc\"><sup>19<\/sup><\/a>.<\/p>\n\n\n\n<p>Poco antes, con motivo de enviar los Cirios bendecidos en la fiesta de la Purificaci\u00f3n, insist\u00eda en el valor de la vida contemplativa: \u00abEl primer destino de los Cirios a las casas religiosas de las m\u00e1s estrictas mortificaciones y penitencias, quiere afirmar una vez m\u00e1s la preeminencia de los deberes del culto y de la consagraci\u00f3n total a la vida de oraci\u00f3n, sobre cualquier otra forma de apostolado, y, al mismo tiempo, subrayar la grandeza y la necesidad de las vocaciones para este g\u00e9nero de vida. Los Cirios encendidos en el austero silencio de tantas casas religiosas, esparcidas por el mundo, ser\u00e1n como la proclamaci\u00f3n de esta necesidad de ap\u00f3stoles santos, y recordar\u00e1n tambi\u00e9n a los ap\u00f3stoles de la vida activa el valor insustituible de la oraci\u00f3n y del renunciamiento para lograr conquistas no ef\u00edmeras, que perduran m\u00e1s all\u00e1 del curso del tiempo\u00bb<a href=\"#sdfootnote20sym\" id=\"sdfootnote20anc\"><sup>20<\/sup><\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">En el momento actual<\/h3>\n\n\n\n<p>\u00bfQu\u00e9 piensa hoy la Iglesia de la vida contemplativa? Basta acudir a los documentos conciliares y a la doctrina del Pont\u00edfice reinante para encontrar la mejor respuesta.<\/p>\n\n\n\n<p>El <strong>Vaticano II<\/strong> recogi\u00f3 las ense\u00f1anzas de Juan XXIII, de todos los dem\u00e1s Pont\u00edfices y de la tradici\u00f3n entera de la Iglesia, y coloc\u00f3 la vida contemplativa en el puesto que merece, saliendo en su defensa y trazando unas directrices nuevas encaminadas a mantener firme el estado mon\u00e1stico, si bien adaptado y renovado seg\u00fan las necesidades de los tiempos, pero partiendo siempre de una vuelta a las fuentes. En el decreto <em>Perfectae caritatis<\/em> hallamos el mejor paneg\u00edrico sobre este g\u00e9nero de vida. \u00abLos institutos puramente contemplativos, de tal modo que sus miembros se dediquen totalmente y solamente a Dios en la soledad y el silencio, con asidua oraci\u00f3n y \u00e1spera penitencia, conservan siempre su importancia, por grande que sea la urgencia del apostolado activo, y ocupan siempre un puesto preeminente en el Cuerpo M\u00edstico de Cristo, en el que todos los miembros no tienen la misma funci\u00f3n. Ya que ellos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ofrecen a Dios el excelso sacrificio de alabanza.<\/li>\n\n\n\n<li>Enriquecen al pueblo de Dios con frutos espl\u00e9ndidos de santidad.<\/li>\n\n\n\n<li>Arrastran con su ejemplo.<\/li>\n\n\n\n<li>Dilatan las obras apost\u00f3licas con su fecundidad misteriosa.<\/li>\n<\/ul>\n\n\n\n<p>De esta forma son la honra de la Iglesia y manantial de gracias celestiales\u00bb.<\/p>\n\n\n\n<p>\u00abCons\u00e9rvese fielmente \u2013insiste el Concilio\u2013 y cada d\u00eda resplandezca m\u00e1s en su genuino esp\u00edritu, tanto en oriente como en occidente, la venerable instituci\u00f3n de la vida mon\u00e1stica, que en el transcurso de los siglos ha obtenido excelentes m\u00e9ritos dentro de la Iglesia y en la sociedad humana\u00bb<a href=\"#sdfootnote21sym\" id=\"sdfootnote21anc\"><sup>21<\/sup><\/a>.<\/p>\n\n\n\n<p><strong>Pablo VI<\/strong>, de innegable mentalidad abierta y renovadora, ha seguido la trayectoria de sus antecesores, y siempre que ha tenido ocasi\u00f3n, ha cantado las excelencias de la vida contemplativa, se\u00f1alando los valores inalienables que encierra.<\/p>\n\n\n\n<p>En 1964, al recibir a un numeroso concurso de Abades, les dirigi\u00f3 breves palabras, repitiendo una vez m\u00e1s el papel fundamental que la vida contemplativa desempe\u00f1a en el Cuerpo M\u00edstico de Cristo. Para desvanecer los equ\u00edvocos que circulaban, de que la vida de consagraci\u00f3n a Dios lejos del mundo era ego\u00edsta y se desentend\u00eda de los problemas de la Iglesia&#8230;, insisti\u00f3 el Papa: \u00abQuiz\u00e1 alguno piense que, por estar encerrados en su clausura, separados del mundo, estos monjes est\u00e1n al margen de la Iglesia. Nada de eso. En realidad, ellos son el coraz\u00f3n de la Iglesia, de los cuales tiene necesidad, y con cuya ayuda cuenta siempre. Los monjes representan los valores, de los cuales hoy m\u00e1s que nunca tiene necesidad la Iglesia\u00bb. Luego sintetiz\u00f3 los medios por los que los contemplativos ejercen su misi\u00f3n en el mundo: \u00abEl recogimiento, la oraci\u00f3n y el amor a la tradici\u00f3n\u00bb. \u00abLos monjes son, adem\u00e1s, los especialistas de la oraci\u00f3n lit\u00fargica\u00bb<a href=\"#sdfootnote22sym\" id=\"sdfootnote22anc\"><sup>22<\/sup><\/a>.<\/p>\n\n\n\n<p>En septiembre de 1968 recibi\u00f3 Pablo VI una misi\u00f3n especial, pocas veces vista en los palacios vaticanos: una comunidad italiana de vida contemplativa, la del Monasterio de Fratoquio, pr\u00f3ximo a la residencia veraniega de Castelgandolfo. En la alocuci\u00f3n que les dirigi\u00f3 encontramos la mejor defensa de la vida contemplativa que se ha podido dar en la situaci\u00f3n actual: \u00abVuestra vocaci\u00f3n \u2013les dec\u00eda el Papa\u2013 ha venido a ser un tanto rara, singular, casi excepcional, puede decirse anacr\u00f3nica; pero la Iglesia, deb\u00e9is saberlo, os expresa toda su estima, os defiende y hace vuestra apolog\u00eda&#8230;\u00bb.<\/p>\n\n\n\n<p>\u00abVuestra vocaci\u00f3n no es anacr\u00f3nica: vosotros no ocup\u00e1is en la Iglesia un puesto in\u00fatil. \u00a1M\u00e1s bien se os es debido! Somos Nos los que tomamos vuestra defensa, los que os hacemos la apolog\u00eda; es la misma Iglesia la que se pone de vuestra parte. Os lo repetimos con todo el coraz\u00f3n: la Iglesia os estima, la Iglesia os ama, la Iglesia os mira a vosotros\u00bb<a href=\"#sdfootnote23sym\" id=\"sdfootnote23anc\"><sup>23<\/sup><\/a>.<\/p>\n\n\n\n<p>Lleg\u00f3 a decir que si la vida contemplativa no estuviera en auge en la hora actual, la Iglesia se ver\u00eda obligada a crearla: \u00abVuestra vocaci\u00f3n es por lo mismo tan hermosa en el concierto de alabanzas que la Iglesia eleva a Dios y a Jesucristo, su Se\u00f1or y Salvador, que, si antes de ahora no existiera, ella deber\u00eda crearla, deber\u00eda inventarla\u00bb.<\/p>\n\n\n\n<p>Recalca sin cesar: \u00abVuestra misi\u00f3n es la plegaria, es la comuni\u00f3n con Dios, es la alabanza a Dios: vosotros sois los profesionales, los especialistas de la oraci\u00f3n. En estos momentos la Iglesia, por Nuestra voz, os habla: y conoce el important\u00edsimo deber que en ella desempe\u00f1\u00e1is. La Iglesia y Nos mismo os lo agradecemos\u00bb.<\/p>\n\n\n\n<p>La misi\u00f3n contemplativa redunda, adem\u00e1s, en provecho de toda la Iglesia. De ella necesita la Iglesia para custodiar su vida, aumentarla m\u00e1s y m\u00e1s. La Iglesia necesita en absoluto almas con la fuerza de la vida interior, sol\u00edcitas s\u00f3lo de unirse a Dios y de ser inflamadas del todo por el amor de las cosas celestiales. Si llegaran a faltar esas almas, si su vida languideciese y se debilitase, se seguir\u00eda necesariamente una p\u00e9rdida de fuerzas en todo el Cuerpo M\u00edstico de Cristo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfCu\u00e1l debe ser vuestra postura, vuestra respuesta, en la hora actual, a las esperanzas de la Iglesia?<\/h3>\n\n\n\n<p>La misi\u00f3n de los contemplativos en estos momentos de incertidumbre es mantenerse en una fidelidad plena y absoluta a las exigencias de su vocaci\u00f3n espec\u00edfica. La Iglesia quiere que sig\u00e1is, con generosidad cada d\u00eda renovada, el camino emprendido del servicio de Dios. Pensad que vuestra vida \u2013quiz\u00e1 un tanto mon\u00f3tona y sin horizonte a primera vista\u2013 es de una trascendencia inmensa en la hora actual de la Iglesia. El deber de cada d\u00eda exactamente cumplido, el vivir sometidas a la obediencia un a\u00f1o y otro, sin desfallecer lo m\u00e1s m\u00ednimo, el abrazarse con entra\u00f1able amor a todos los sacrificios impuestos por las reglas, la oraci\u00f3n asidua y ferviente en el coro y en las dem\u00e1s tareas&#8230;, he aqu\u00ed otros tantos medios excelentes de perfeccionamiento e irradiaci\u00f3n espiritual.<\/p>\n\n\n\n<p>Vosotras no necesit\u00e1is salir al mundo para ser testigos del Se\u00f1or, hoy que tanto se habla de dar testimonio: perder\u00edais lastimosamente el tiempo. Lo dec\u00eda Pablo VI no hace muncho: \u00abVuestro testimonio, es cierto, no todos lo perciben, porque la vida contemplativa se acerca tanto al misterio de Dios, que el mundo no la entiende. No hag\u00e1is, por tanto, esfuerzos para ser de alguna manera comprendidas por los hombres, porque esto tal vez os conducir\u00eda a p\u00e9rdidas deplorables. Sed lo que sois, y Dios cuidar\u00e1 de que vuestra luz brille ante los hombres\u00bb.<\/p>\n\n\n\n<p>Las almas contemplativas est\u00e1is obligadas a una santidad de vida superior a la del com\u00fan de los fieles; de lo contrario cometer\u00edais un fraude a las esperanzas de la Iglesia. De nada sirve vivir encerradas en una clausura, alejadas por completo del mundo, si sois contemplativas s\u00f3lo de nombre. Sed conscientes de la responsabilidad que pesa sobre vosotras, si no llen\u00e1is los altos fines de vuestra vocaci\u00f3n. Si San Alfonso Mar\u00eda de Ligorio culpaba a los sacerdotes no fieles de ser, al menos en parte, la causa de que el mundo no fuera mejor; podemos a\u00f1adir, por nuestra parte, que, si la vida mon\u00e1stica es desestimada y no irradia con fuerza la luz del Evangelio, tal vez se deba a que las almas contemplativas \u2013verdadera \u00absal de la tierra\u00bb\u2013 no viven en plenitud su consagraci\u00f3n con todas las exigencias que impone.<\/p>\n\n\n\n<p>No olvid\u00e9is lo que dec\u00eda aquel joven citado m\u00e1s arriba, gran contemplativo y lleno de experiencia de Dios: \u00abJes\u00fas necesita corazones que, olvidados de s\u00ed mismos y lejos del mundo, adoren y amen con frenes\u00ed y con locura su Coraz\u00f3n dolorido y desgarrado por tanto olvido\u00bb<a href=\"#sdfootnote24sym\" id=\"sdfootnote24anc\"><sup>24<\/sup><\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Reflexi\u00f3n final<\/h2>\n\n\n\n<p>No quisiera terminar esta carta pastoral, queridas religiosas de San Clemente, sin referirme, con suma brevedad, a aquel de quien sois hijas: el gran San Bernardo. La reforma que \u00e9l emprendi\u00f3 en el siglo XII dio en seguida frutos copiosos. Al final de ese siglo, quinientas treinta Casas de Cistercienses, pobres y austeras, hab\u00edan surgido en Europa. Lo mismo las comunidades de varones que las de mujeres se dejaron poseer por aquella m\u00edstica del \u00abdivino amor\u00bb, de la que Bernardo tuvo el secreto. Vuestro Monasterio fue una de esas Casas donde habit\u00f3 la luz. Perteneciente en sus or\u00edgenes a la gran familia benedictina, vuestro Monasterio quiso tambi\u00e9n retomar a la observancia fiel de la regla de San Benito, que no otro fue el empe\u00f1o de Bernardo de Claraval, Caballero de Cristo. Vuestras antepasadas, las monjas cuyos restos conserv\u00e1is bajo el polvo de los sepulcros, supieron dar magn\u00edficos ejemplos de santidad que vinieron a confluir en el gran torrente, la espiritualidad de la Edad Media cristiana.<\/p>\n\n\n\n<p>Haced cuanto pod\u00e1is para fortalecer vuestras comunidades, para conservar vuestros Monasterios dignamente, para tener a mano los medios indispensables que exige la adecuada formaci\u00f3n de vuestras novicias y profesas. Ello debe ser objeto de continua reflexi\u00f3n y oportunas decisiones en vuestra Orden.<\/p>\n\n\n\n<p>De lo que s\u00ed pod\u00e9is estar seguras es de que hoy sois tan actuales como ayer. La Iglesia y el mundo necesitan de vuestra presencia silenciosa y oculta, de vuestra oraci\u00f3n y sacrificio, de vuestra delicadeza y vuestro temple ardoroso para vivir en la fe y en el amor.<\/p>\n\n\n\n<p>Que este Octavo Centenario renueve en vuestro Monasterio los d\u00edas de gloria a Dios y de servicio a la Iglesia como en otros tiempos, y os ayude a mantener la fidelidad de vuestro esp\u00edritu a los compromisos de la vida religiosa que hab\u00e9is aceptado con amor.<\/p>\n\n\n\n<p><a href=\"#sdfootnote1anc\" id=\"sdfootnote1sym\">1<\/a> Cfr. <em>Summa Theologiae<\/em>, 2-2 q. 181 a. I.<\/p>\n\n\n\n<p><a href=\"#sdfootnote2anc\" id=\"sdfootnote2sym\">2<\/a> Cfr. San Gregorio Magno, <em>Exposici\u00f3n de 1Reg. 1-5,<\/em>IV, 68.<\/p>\n\n\n\n<p><a href=\"#sdfootnote3anc\" id=\"sdfootnote3sym\">3<\/a> <em>De <\/em><em>consideration<\/em><em>e<\/em>, II, 2.<\/p>\n\n\n\n<p><a href=\"#sdfootnote4anc\" id=\"sdfootnote4sym\">4<\/a> J. Card. Bona, <em>Via compendii ad Deum, <\/em>en <em>Opera Omnia, <\/em>Venetti 1764, c.9. n.4.<\/p>\n\n\n\n<p><a href=\"#sdfootnote5anc\" id=\"sdfootnote5sym\">5<\/a> Cfr. Abad Tritemio, <em>Homil\u00eda XII.<\/em><\/p>\n\n\n\n<p><a href=\"#sdfootnote6anc\" id=\"sdfootnote6sym\">6<\/a> <em>Homil\u00eda 69 sobre San Mateo.<\/em><\/p>\n\n\n\n<p><a href=\"#sdfootnote7anc\" id=\"sdfootnote7sym\">7<\/a> San Jer\u00f3nimo, <em>Carta a Eustoquia,<\/em>4.<\/p>\n\n\n\n<p><a href=\"#sdfootnote8anc\" id=\"sdfootnote8sym\">8<\/a> San Agust\u00edn, <em>Confesiones,<\/em>1,2.<\/p>\n\n\n\n<p><a href=\"#sdfootnote9anc\" id=\"sdfootnote9sym\">9<\/a> San Jer\u00f3nimo<em>, <\/em><em>Comentario a Isa\u00edas<\/em>;PL 25, 18<em><strong>.<\/strong><\/em><\/p>\n\n\n\n<p><a href=\"#sdfootnote10anc\" id=\"sdfootnote10sym\">10<\/a> C. Marmion, <em>Jesucristo, ideal del monje<\/em>,Barcelona 1949, 447.<\/p>\n\n\n\n<p><a href=\"#sdfootnote11anc\" id=\"sdfootnote11sym\">11<\/a> <em>Sermones sobre el Cantar de los Cantares, <\/em>Serm\u00f3n 57, 9: <em>Obras completas de San Bernardo, <\/em>II, Madrid 1955, BAC 130, 379.<\/p>\n\n\n\n<p><a href=\"#sdfootnote12anc\" id=\"sdfootnote12sym\">12<\/a> <em>Sermones sobre el Cantar de los Cantares<\/em>, Serm\u00f3n10 y Serm\u00f3n 46; <em>o. c.,<\/em> 53-56 310-315.<\/p>\n\n\n\n<p><a href=\"#sdfootnote13anc\" id=\"sdfootnote13sym\">13<\/a> Cf. M. Philippon. <em>La doctrina espiritual de Sor Isabel de la Trinidad,<\/em> Buenos Aires 1942, 190.<\/p>\n\n\n\n<p><a href=\"#sdfootnote14anc\" id=\"sdfootnote14sym\">14<\/a> <em>Saber esperar,<\/em> Venta de Ba\u00f1os (Palencia) 1962, 149-150.<\/p>\n\n\n\n<p><a href=\"#sdfootnote15anc\" id=\"sdfootnote15sym\">15<\/a> Abad\u00eda de la Pierre qui-vire, <em>Monjes,<\/em> Madrid 1955, 123.<\/p>\n\n\n\n<p><a href=\"#sdfootnote16anc\" id=\"sdfootnote16sym\">16<\/a> Constituci\u00f3n <em>Umbratilem,<\/em> 8 de agosto de 1924.<\/p>\n\n\n\n<p><a href=\"#sdfootnote17anc\" id=\"sdfootnote17sym\">17<\/a> <em>Divini Redemptoris,<\/em>62.<\/p>\n\n\n\n<p><a href=\"#sdfootnote18anc\" id=\"sdfootnote18sym\">18<\/a> Mensaje de P\u00edo XII, transmitido por radio a las monjas de clausura los d\u00edas 19 y 26 de julio y 2 de agosto de 1958. Texto completo en su original franc\u00e9s en: P\u00edo XII, <em>Discorsi e radiomessaggi,<\/em> XX, 245-270.<\/p>\n\n\n\n<p><a href=\"#sdfootnote19anc\" id=\"sdfootnote19sym\">19<\/a> Alocuci\u00f3n a los Abades del C\u00edster, 1 de noviembre de 1961.<\/p>\n\n\n\n<p><a href=\"#sdfootnote20anc\" id=\"sdfootnote20sym\">20<\/a> Homil\u00eda del 2 de febrero de 1961, en la festividad lit\u00fargica de la Purificaci\u00f3n de la Virgen.<\/p>\n\n\n\n<p><a href=\"#sdfootnote21anc\" id=\"sdfootnote21sym\">21<\/a> PC 9.<\/p>\n\n\n\n<p><a href=\"#sdfootnote22anc\" id=\"sdfootnote22sym\">22<\/a> Discurso con motivo de la reconstrucci\u00f3n de la abad\u00eda de Montecasino, 24 de octubre de 1964.<\/p>\n\n\n\n<p><a href=\"#sdfootnote23anc\" id=\"sdfootnote23sym\">23<\/a> Discurso de 14 de septiembre de 1968, a los Capitulares de varias \u00f3rdenes religiosas contemplativas.<\/p>\n\n\n\n<p><a href=\"#sdfootnote24anc\" id=\"sdfootnote24sym\">24<\/a> Fr. M\u00aa Rafael, <em>Saber esperar,<\/em> n. 330.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carta pastoral, de mayo de 1977, con motivo del VIII Centenario del Monasterio Cisterciense de San Clemente, de Toledo. Texto publicado en el Bolet\u00edn Oficial del Arzobispado de Toledo, mayo 1977. No hace mucho tiempo, con motivo de la canonizaci\u00f3n de Santa Beatriz de Silva y de la beatificaci\u00f3n de Sor Mar\u00eda de Jes\u00fas, pude [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"saved_in_kubio":false,"_eb_attr":"","ngg_post_thumbnail":0,"footnotes":""},"doc_category":[52],"doc_tag":[],"class_list":["post-720","docs","type-docs","status-publish","hentry","doc_category-vida-contemplativa"],"year_month":"2026-05","word_count":8180,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"P. Webmaster","author_nicename":"currante","author_url":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/author\/currante\/"},"doc_category_info":[{"term_name":"Vida contemplativa","term_url":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/docs-category\/vida-contemplativa\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs\/720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/comments?post=720"}],"version-history":[{"count":1,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs\/720\/revisions"}],"predecessor-version":[{"id":721,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs\/720\/revisions\/721"}],"wp:attachment":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/media?parent=720"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/doc_category?post=720"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/doc_tag?post=720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}