{"id":1678,"date":"2024-10-01T19:07:54","date_gmt":"2024-10-01T17:07:54","guid":{"rendered":"https:\/\/www.cardenaldonmarcelo.es\/?post_type=docs&#038;p=1678"},"modified":"2024-10-01T19:07:56","modified_gmt":"2024-10-01T17:07:56","password":"","slug":"no-podemos-reservarnos-nada-comentario-a-las-lecturas-del-xxxiii-domingo-del-tiempo-ordinario-ciclo-a","status":"publish","type":"docs","link":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/docs\/no-podemos-reservarnos-nada-comentario-a-las-lecturas-del-xxxiii-domingo-del-tiempo-ordinario-ciclo-a\/","title":{"rendered":"No podemos reservarnos nada, comentario a las lecturas del XXXIII domingo del Tiempo Ordinario (ciclo A)"},"content":{"rendered":"\n<p class=\"has-text-align-center has-small-font-size wp-block-paragraph\">Comentario a las lecturas del XXXIII domingo del Tiempo Ordinario. ABC, 17 de noviembre de 1996.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seguimos en la misma l\u00ednea del comentario del domingo anterior. Tanto san Pablo, en la carta a la comunidad de Tesal\u00f3nica, como Jes\u00fas, en el evangelio, se pronuncian sobre el \u00faltimo fin del hombre y del mundo. Los textos de hoy subrayan a\u00fan de manera m\u00e1s en\u00e9rgica nuestra responsabilidad personal en el quehacer diario, como decisivo para nuestro destino eterno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la lectura del libro de los Proverbios se nos ilumina el coraz\u00f3n ante la sencilla, pero exigente vida de la mujer hacendosa. Vida de trabajo al servicio de la familia y de los necesitados. Es alabada por el \u00e9xito de su laboriosidad, por su actitud en el hogar, y por su generosidad para con los pobres. Mujer de aut\u00e9nticos valores y de riqueza interior, que se consolida con el tiempo, aunque pase la belleza de la juventud. Escueto y sencillo el texto que, no obstante, refleja todo un estilo de vida, que proporciona felicidad en su entorno, que renuncia al brillo fugaz y superficial de los \u00e9xitos mundanos, y valora ante todo el obsequio a Dios, la armoniosa y abnegada vida de familia y la ayuda a los dem\u00e1s. Una vida as\u00ed se ensalza por s\u00ed misma, y sirve de ejemplo por su dignidad y su se\u00f1or\u00edo. Muchas mujeres de nuestro tiempo se distinguen tambi\u00e9n por ese encanto de su juventud y su belleza, pero tienen las manos vac\u00edas, la cabeza vac\u00eda, y el coraz\u00f3n vac\u00edo, y cuando llegan a la edad, que las hace merecedoras de estimaci\u00f3n y de respeto por el noble sacrificio, que las acompa\u00f1\u00f3 toda su vida, aparecen empeque\u00f1ecidas y pobres, cuando pod\u00edan mostrar con leg\u00edtimo orgullo el tesoro de sus virtudes. No hay rostro hermoso, cuando la fealdad del ego\u00edsmo mancha las almas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dichoso quien teme al Se\u00f1or, porque ese temor le llevar\u00e1 a vivir del fruto del propio trabajo y no del fraude y del enga\u00f1o. La mujer ser\u00e1 como parra fecunda y los hijos como renuevos de olivo alrededor de la mesa. Formar un verdadero hogar es hoy una empresa de la m\u00e1s alta categor\u00eda humana y social. La sociedad opulenta, a la que sobra todo, tiene los d\u00edas contados, si sigue olvid\u00e1ndose de los que no tienen ni pan, ni trabajo. Se producir\u00e1n reclamaciones violent\u00edsimas, porque est\u00e1n cada vez m\u00e1s cerca los que conocen todo, aunque les falte todo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La certeza de la venida del Se\u00f1or nos debe llevar a una actitud de vigilancia y vida honrada, tal como san Pablo nos lo recuerda insistentemente. Pero no solamente honrada; ha de ser tambi\u00e9n cristiana, porque es lo que Cristo nos pidi\u00f3, cuando se nos mostr\u00f3 como camino, verdad y vida. La idea del juicio est\u00e1 cimentando el fragmento del evangelio de san Mateo, que leemos hoy. Somos colaboradores de Dios, cooperadores con \u00c9l no s\u00f3lo en cuanto ata\u00f1e a lo moral profesional y a las responsabilidades, que hemos de asumir en la sociedad, en que vivimos. El cristiano es el hombre nuevo, que tiene que propagar su fe, poner en pie con su esperanza a los deca\u00eddos y desesperados, y amar como Cristo nos am\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No podemos guardar nada para evitar que se nos pierda. Hay que administra bien seg\u00fan Dios todo lo recibido. La fidelidad a lo recibido ha de traducirse en coraje, generosidad y entrega. Aquel hombre, que recibi\u00f3 cinco talentos y negoci\u00f3 con ellos hasta lograr otros cinco es el modelo. Tenemos en esta par\u00e1bola el modelo del cristiano, el luchador por la causa de Cristo, el misionero constante dentro de su vida sencilla y normal. Un hombre o una mujer cristianos no pueden ser indiferentes ante el olvido de Dios, en que hoy naufragan tantos seres humanos, tantos amigos, tantos hijos y familias suyos. Hemos de abrir nuestro coraz\u00f3n a Dios para ver todo lo que exige de cada uno de nosotros en relaci\u00f3n con lo que se nos ha dado. Seremos juzgados por Jes\u00fas en lo que constituye nuestro cotidiano vivir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comentario a las lecturas del XXXIII domingo del Tiempo Ordinario. ABC, 17 de noviembre de 1996. Seguimos en la misma l\u00ednea del comentario del domingo anterior. Tanto san Pablo, en la carta a la comunidad de Tesal\u00f3nica, como Jes\u00fas, en el evangelio, se pronuncian sobre el \u00faltimo fin del hombre y del mundo. Los textos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"saved_in_kubio":false,"_eb_attr":"","ngg_post_thumbnail":0,"footnotes":""},"doc_category":[79],"doc_tag":[],"class_list":["post-1678","docs","type-docs","status-publish","hentry","doc_category-comentarios-a-evangelios-dominicales"],"year_month":"2026-07","word_count":710,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"P. Webmaster","author_nicename":"currante","author_url":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/author\/currante\/"},"doc_category_info":[{"term_name":"Comentarios a evangelios dominicales","term_url":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/docs-category\/comentarios-a-evangelios-dominicales\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs\/1678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/comments?post=1678"}],"version-history":[{"count":1,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs\/1678\/revisions"}],"predecessor-version":[{"id":1679,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs\/1678\/revisions\/1679"}],"wp:attachment":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/media?parent=1678"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/doc_category?post=1678"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/doc_tag?post=1678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}