{"id":1519,"date":"2024-09-30T23:20:02","date_gmt":"2024-09-30T21:20:02","guid":{"rendered":"https:\/\/www.cardenaldonmarcelo.es\/?post_type=docs&#038;p=1519"},"modified":"2024-09-30T23:20:03","modified_gmt":"2024-09-30T21:20:03","password":"","slug":"dos-ayudas-para-la-catequesis","status":"publish","type":"docs","link":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/docs\/dos-ayudas-para-la-catequesis\/","title":{"rendered":"Dos ayudas para la catequesis"},"content":{"rendered":"\n<p class=\"has-text-align-center has-small-font-size\">Pr\u00f3logo a dos obras del Dr. Benjam\u00edn Mart\u00edn S\u00e1nchez tituladas \u00abBreve teolog\u00eda\u00bb y \u00abLa religi\u00f3n cat\u00f3lica\u00bb, 1977.<\/p>\n\n\n\n<p>Una de las necesidades m\u00e1s fuertemente sentidas en nuestro tiempo es la de una instrucci\u00f3n religiosa s\u00f3lida, coherente, bien fundada.<\/p>\n\n\n\n<p>No basta hablar de religi\u00f3n, de Cristo, del cristianismo. Es necesario conocer el contenido de la Revelaci\u00f3n y saber dar raz\u00f3n del mismo, con exactitud proporcionada a la cultura de cada uno. Para lograrlo se est\u00e1n haciendo esfuerzos notables por pedagogos catequistas de nuestros d\u00edas, no siempre con acierto.<\/p>\n\n\n\n<p>Creemos que estos libros <em>Breve teolog\u00eda<\/em> y <em>La religi\u00f3n cat\u00f3lica<\/em>, escritos por el benem\u00e9rito y culto sacerdote, M. I. Sr. D. Benjam\u00edn Mart\u00edn S\u00e1nchez, pueden ayudar mucho a alcanzar esa formaci\u00f3n tan deseada. En ellos hay conceptos claros y ordenados, f\u00f3rmulas f\u00e1ciles de retener, fundamentaci\u00f3n b\u00edblica y adecuada explicaci\u00f3n teol\u00f3gica, iluminaci\u00f3n suficiente del Magisterio de la Iglesia, siguiendo el Credo del Pueblo de Dios.<\/p>\n\n\n\n<p>Sin duda ser\u00e1n muy provechosos en manos de alumnos y educadores de la fe para el trabajo en escuelas y catequesis.<\/p>\n\n\n\n<p>Toledo, junio 1977<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00f3logo a dos obras del Dr. Benjam\u00edn Mart\u00edn S\u00e1nchez tituladas \u00abBreve teolog\u00eda\u00bb y \u00abLa religi\u00f3n cat\u00f3lica\u00bb, 1977. Una de las necesidades m\u00e1s fuertemente sentidas en nuestro tiempo es la de una instrucci\u00f3n religiosa s\u00f3lida, coherente, bien fundada. No basta hablar de religi\u00f3n, de Cristo, del cristianismo. Es necesario conocer el contenido de la Revelaci\u00f3n y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"saved_in_kubio":false,"_eb_attr":"","ngg_post_thumbnail":0,"footnotes":""},"doc_category":[75],"doc_tag":[],"class_list":["post-1519","docs","type-docs","status-publish","hentry","doc_category-prologos"],"year_month":"2026-05","word_count":203,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"P. Webmaster","author_nicename":"currante","author_url":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/author\/currante\/"},"doc_category_info":[{"term_name":"Pr\u00f3logos","term_url":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/docs-category\/prologos\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs\/1519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/comments?post=1519"}],"version-history":[{"count":1,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs\/1519\/revisions"}],"predecessor-version":[{"id":1520,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs\/1519\/revisions\/1520"}],"wp:attachment":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/media?parent=1519"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/doc_category?post=1519"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/doc_tag?post=1519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}