{"id":1418,"date":"2024-09-29T23:15:13","date_gmt":"2024-09-29T21:15:13","guid":{"rendered":"https:\/\/www.cardenaldonmarcelo.es\/?post_type=docs&#038;p=1418"},"modified":"2024-09-29T23:15:14","modified_gmt":"2024-09-29T21:15:14","password":"","slug":"el-sacerdocio-de-nuestra-epoca","status":"publish","type":"docs","link":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/docs\/el-sacerdocio-de-nuestra-epoca\/","title":{"rendered":"El sacerdocio de nuestra \u00e9poca"},"content":{"rendered":"\n<p class=\"has-text-align-center has-small-font-size wp-block-paragraph\">Pr\u00f3logo al libro del P Juan Carrascal, S.I., titulado \u00abSobre el sacerdocio\u00bb, 1965.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Escribo estas l\u00edneas, cuando corren los \u00faltimos d\u00edas de la tercera sesi\u00f3n del Concilio Vaticano II. Todas las ma\u00f1anas acudimos los Padres Conciliares donde, entre alegr\u00edas y dolores, se est\u00e1n poniendo los cimientos para una nueva vida de la Iglesia. El sol no ha dejado de brillar, a pesar de estar muy avanzado el oto\u00f1o, y una luz suave y fin\u00edsima se filtra a trav\u00e9s de los grandes ventanales del maravilloso Templo, como un obsequio que el cielo romano quisiera hacer a cuantos dentro del Aula Conciliar deliberan sobre los problemas de la Iglesia. Precisamente hoy, 16 de noviembre, es el segundo d\u00eda que el concilio dedica a hablar de los seminarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que se dice, juntamente con lo tratado en otros esquemas conciliares, aspira a se\u00f1alar las l\u00edneas generales de la figura del sacerdote de nuestra \u00e9poca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ser\u00e1 un sacerdote abierto al mundo, renovador, sincero, pose\u00eddo de un ansia inmensa de evangelizaci\u00f3n, lleno de amor a la Iglesia santa de Dios, elevado sobre las estructuras humanas, en que el mundo se mueve, con su confianza puesta en la gracia y los dones divinos, dispuesto siempre a servir, nunca buscando ser servido. Es decir, lo que han sido siempre los santos de verdad en su entrega al ministerio apost\u00f3lico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Porque \u00e9sta es la manera de entender la adaptaci\u00f3n que se busca. Nadie piense que se trata de una modernizaci\u00f3n consistente en condescendencias, al arbitrio de cada uno. El amor al hombre y al mundo, en que \u00e9ste vive, no significa, para el sacerdote, la m\u00e1s m\u00ednima renuncia a lo que tiene de espec\u00edfico una vida sacerdotal: su uni\u00f3n con Jesucristo. En la medida en que esta uni\u00f3n se logre o se quebrante, se vivir\u00e1 el sacerdocio con dignidad o sin ella. Ahora bien, no se puede estar unido con Jesucristo sin amar lo que \u00c9l am\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y es en el seminario, de ley ordinaria, donde esta uni\u00f3n se preparar con paciencia y humildad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De ah\u00ed la utilidad inmensa que puede prestar este libro, que el autor pone en manos de los seminaristas. Una sabia conjunci\u00f3n de asc\u00e9tica cl\u00e1sica, de piedad lit\u00fargica, de reflexiones, que facilitan la pr\u00e1ctica de la meditaci\u00f3n y del examen continuo sobre s\u00ed mismo y sobre las cosas que le rodean, abre ante los ojos del seminarista un horizonte ampl\u00edsimo para la reflexi\u00f3n y la plegaria. El que siga su camino de mano de este libro, a trav\u00e9s de las diversas etapas de la vida del seminario, tiene todas las garant\u00edas de acierto para lograr esa condici\u00f3n b\u00e1sica e indispensable, sin la cual es una temeridad acercarse al sacerdocio: la docilidad a la gracia, y la acci\u00f3n amorosa del Esp\u00edritu Santo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Iglesia pide y espera sacerdotes \u2013y por consiguiente seminaristas\u2013 conscientes del valor sobrenatural ante todo y sobre todo; sacrificados y humildes; obedientes por amor y por convicci\u00f3n; pobres y amantes de la pobreza; cultos en las ciencias sagradas y suficientemente instruidos en las profanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Respetuosos de las sabias tradiciones y renovadores de cuanto deba ser renovado dentro del orden, la colaboraci\u00f3n y la concordia. Sacerdotes, que de una vez para siempre se den cuenta de que para que su acci\u00f3n en el mundo sea eficazmente salvadora, conforme a la intenci\u00f3n de Cristo, no hacen falta cr\u00edticas amargas y destempladas, posturas modernistas y vacuas, activismos disipadores y mundanizantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El m\u00e1s avanzado misionero de vanguardia y el m\u00e1s tranquilo p\u00e1rroco de una comunidad cristiana de las piadosas tierras de Espa\u00f1a necesitan por igual de una cosa para que su ministerio sea lo que tiene que ser. Necesitan de una uni\u00f3n \u00edntima y profunda con Jesucristo, para que su sacerdocio sea el sacerdocio de Cristo. Si no es as\u00ed, no tienen nada que hacer en los campos del Se\u00f1or; y mejor ser\u00eda que se retirasen a tiempo. Con esto de base y sin perderlo de vista jam\u00e1s, vengan despu\u00e9s los intentos de renovaci\u00f3n necesarios. Venga la cr\u00edtica y la revisi\u00f3n, en uni\u00f3n con los dem\u00e1s y con su Obispo; vengan la autenticidad y el di\u00e1logo; la b\u00fasqueda incesante de nuevos m\u00e9todos de evangelizaci\u00f3n; el deslinde noble y sincero entre lo que es accesorio y lo fundamental en todas las estructuras, por donde hemos de movernos para llevar a los hombres el Evangelio de Jes\u00fas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin esa fundamentaci\u00f3n, vivida hasta las \u00faltimas consecuencias, mucho me temo que la autenticidad se reduzca a palabrer\u00eda vana; la cr\u00edtica a nuevo af\u00e1n de liberaciones ego\u00edstas; la lucha apost\u00f3lica, a una miserable caricatura de lo que han hecho siempre los verdaderos ap\u00f3stoles de Dios, siempre modernos sea cual sea el siglo en que vivieron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estoy convencido de que los seminarios espa\u00f1oles necesitan tambi\u00e9n de una profunda renovaci\u00f3n en esta hora humilde y hermosa de la Iglesia, en que todo quiere ser renovado. Pero hay un punto de partida inconmovible, sin el cual nada se puede hacer, y es \u00e9ste: el seminarista, desde que entra en el seminario, tiene que esforzarse por dominar sus pasiones desordenadas y aspirar a un progreso continuo en el desarrollo de sus virtudes humanas y sobrenaturales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Creo que el libro del P. Carrascal puede ser un valios\u00edsimo instrumento para lograrlo. Se necesitar\u00e1n, sin duda, otros libros y otros instrumentos, que desarrollen m\u00e1s ampliamente aspectos parciales de la formaci\u00f3n espiritual y humana del seminarista, muchos de los cuales existen ya, mientras que otros seguir\u00e1n apareciendo. Pero es necesario que antes de que el seminarista reflexione sobre esas perspectivas m\u00e1s particulares de la piedad y de la vida, se acostumbre a ver el panorama general de las virtudes y los peligros, del mundo y del seminario, del cuerpo y del alma, de la ma\u00f1ana y de la tarde, del sufrimiento y del gozo, de la oraci\u00f3n y del trabajo, de la amistad y del esfuerzo aislado, es decir, de todo lo que constituye su vida hacia el sacerdocio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De ah\u00ed la utilidad de este libro. Es sencillo, s\u00f3lido, completo. Est\u00e1 dictado por la experiencia y el amor. Lo que dice y ofrece es como la columna vertebral para la vida del esp\u00edritu, que m\u00e1s tarde el seminarista ir\u00e1 enriqueciendo y desarrollando progresivamente. Empecemos por ah\u00ed y despu\u00e9s vendr\u00e1 lo dem\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los miles de alumnos, que en los seminarios de Espa\u00f1a juegan, rezan, y estudian juntos, tienen el mismo derecho que los dem\u00e1s a recibir lo que necesitan de renovaci\u00f3n para su trabajo en el mundo que les espera; y tambi\u00e9n a pedirnos que sepamos cumplir con nuestro deber manteniendo lo que tiene valor permanente y seguro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Roma, noviembre 1964<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00f3logo al libro del P Juan Carrascal, S.I., titulado \u00abSobre el sacerdocio\u00bb, 1965. Escribo estas l\u00edneas, cuando corren los \u00faltimos d\u00edas de la tercera sesi\u00f3n del Concilio Vaticano II. Todas las ma\u00f1anas acudimos los Padres Conciliares donde, entre alegr\u00edas y dolores, se est\u00e1n poniendo los cimientos para una nueva vida de la Iglesia. El sol [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"saved_in_kubio":false,"_eb_attr":"","ngg_post_thumbnail":0,"footnotes":""},"doc_category":[75,29],"doc_tag":[],"class_list":["post-1418","docs","type-docs","status-publish","hentry","doc_category-prologos","doc_category-sacerdocio"],"year_month":"2026-07","word_count":1178,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"P. Webmaster","author_nicename":"currante","author_url":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/author\/currante\/"},"doc_category_info":[{"term_name":"Pr\u00f3logos","term_url":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/docs-category\/prologos\/"},{"term_name":"Sacerdocio","term_url":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/docs-category\/sacerdocio\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs\/1418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/comments?post=1418"}],"version-history":[{"count":1,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs\/1418\/revisions"}],"predecessor-version":[{"id":1419,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/docs\/1418\/revisions\/1419"}],"wp:attachment":[{"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/media?parent=1418"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/doc_category?post=1418"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.cardenaldonmarcelo.es\/index.php\/wp-json\/wp\/v2\/doc_tag?post=1418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}